{"id":16587,"date":"2025-07-26T03:17:16","date_gmt":"2025-07-26T03:17:16","guid":{"rendered":"https:\/\/fts-travel.com\/tours\/sahl-hasheesh-desert-stargazing-candlelight-bbq-dinner-t671438-ranking_uuid4016277b-0d6b-4e35-b9d6-ab275caa7205\/"},"modified":"2025-07-26T03:19:12","modified_gmt":"2025-07-26T03:19:12","slug":"sahl-hasheesh-desert-stargazing-candlelight-bbq-dinner-t671438-ranking_uuid4016277b-0d6b-4e35-b9d6-ab275caa7205","status":"publish","type":"trip","link":"https:\/\/fts-travel.com\/es\/tours\/sahl-hasheesh-desert-stargazing-candlelight-bbq-dinner-t671438-ranking_uuid4016277b-0d6b-4e35-b9d6-ab275caa7205\/","title":{"rendered":"Sahl Hasheesh: Observaci\u00f3n de estrellas en el desierto, cena a la luz de las velas y barbacoa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":19416,"comment_status":"open","ping_status":"closed","template":"","destination":[],"activities":[],"trip_types":[],"packages":[],"class_list":["post-16587","trip","type-trip","status-publish","has-post-thumbnail","hentry","travel-monster-post","latest_post"],"packages_ids":"","trip_extras":[],"cut_off_time":{"enabled":true,"duration":1,"duration_unit":"d\u00edas"},"booked-seats":[],"trip_extra_services":{},"acf":[],"trip_version":"2.0.0","_s_has_sale":"no","_edit_lock":"1753499908:1","total_travellers_per_day":"","wp_travel_engine_setting":{"trip_code":"FTS-16582","overview_section_title":"Visi\u00f3n general","tab_content":{"1_wpeditor":"<!-- wp:paragraph -->\n<p>Deje atr\u00e1s la ciudad y emb\u00e1rquese en una m\u00e1gica aventura por el desierto en Sahl Hasheesh. Comience su viaje con un emocionante paseo por las dunas doradas, donde podr\u00e1 contemplar el impresionante paisaje del desierto durante la puesta de sol. Al llegar al campamento de estilo beduino, le recibir\u00e1n con hospitalidad tradicional y disfrutar\u00e1 de una cena a la barbacoa reci\u00e9n preparada bajo el cielo abierto.  <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Al caer la noche, sum\u00e9rjase en el silencio y la belleza del desierto. Con la ayuda de gu\u00edas expertos y telescopios de alta potencia, explore las maravillas del cielo nocturno, detecte constelaciones, planetas e incluso galaxias lejanas. Esta experiencia \u00fanica combina aventura, cultura y naturaleza, ofreciendo una escapada tranquila y recuerdos inolvidables.  <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tanto si viaja en pareja, en familia o en solitario, esta excursi\u00f3n para observar las estrellas es la forma perfecta de disfrutar de la belleza de la noche del desierto egipcio.<\/p>\n<!-- \/wp:paragraph -->","8_wpeditor":"","9_wpeditor":"<!-- wp:html -->\n<script defer async=\"\" src=\"https:\/\/cdn.trustindex.io\/loader.js?cf01ce650c758148d126d6d44ef\"><\/script>\n<!-- \/wp:html -->"},"cost_tab_sec_title":"Incluye","cost":{"includes_title":"El coste incluye","cost_includes":"Recogida en el hotel y regreso desde Sahl Hasheesh o Makadi Bay\nGu\u00eda experimentado en el desierto\nObservaci\u00f3n de las estrellas con telescopio\nVisita al campamento beduino\nHorneado de pan\nEspect\u00e1culo beduino\nEspect\u00e1culo de danza\n5 tipos de platos calientes\nFrutas de temporada (2 tipos diferentes)\nRefresco durante la puesta de sol y la cena\nPaseo de 30 minutos en quad (si se selecciona la opci\u00f3n)","excludes_title":"","cost_excludes":""},"trip_duration":7,"trip_duration_unit":"horas","trip_duration_nights":0,"min_max_age_enable":"","trip_cutoff_enable":"1","trip_cut_off_time":1,"trip_cut_off_unit":"d\u00edas","minmax_pax_enable":"","trip_minimum_pax":0,"trip_maximum_pax":0,"map":{"iframe":""},"map_section_title":"","trip_highlights_title":"Destacados","trip_highlights":[{"highlight_text":"Paseo en camello y a caballo por el desierto de Sahl Hasheesh"},{"highlight_text":"Impresionantes vistas de la puesta de sol en el desierto, cena tradicional con barbacoa en un campamento de estilo beduino"},{"highlight_text":"Observaci\u00f3n de las estrellas con telescopios de alta potencia y visita guiada al cielo"},{"highlight_text":"Aut\u00e9ntico ambiente des\u00e9rtico y conocimientos culturales familias y amantes de la aventura"}],"faq_section_title":"Preguntas m\u00e1s frecuentes","faq":{"faq_title":["\u00bfQu\u00e9 debo llevar?","\u00bfQu\u00e9 no est\u00e1 permitido?","\u00bfQu\u00e9 debo saber antes de ir?"],"faq_content":["<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Gafas de sol<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Sombrero para el sol<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>C\u00e1mara<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Protector solar<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Agua<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Efectivo<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->","<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Cochecitos de beb\u00e9<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Maletas o bolsas grandes<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Alcohol y drogas<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->","<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Por favor, inf\u00f3rmenos del nombre de su hotel y n\u00famero de habitaci\u00f3n despu\u00e9s de reservar para organizar la recogida.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La recogida s\u00f3lo est\u00e1 disponible en los hoteles de Sahl Hasheesh y Makadi Bay; en otras zonas pueden aplicarse cargos adicionales.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La excursi\u00f3n se realiza en todoterreno, por lo que no est\u00e1 recomendada para personas con problemas de movilidad.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La observaci\u00f3n de las estrellas depende de las condiciones meteorol\u00f3gicas y puede modificarse en caso de viento fuerte o nubes.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Pres\u00e9ntese en el vest\u00edbulo del hotel al menos 10 minutos antes de la hora de recogida programada.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->"]},"enable_video_gallery":"","itinerary":{"itinerary_title":{"1":"Bah\u00eda de Makadi, El Gouna, Sahl Hasheesh, Hurghada, Safaga","2":"(30 minutos)","3":"(15 minutos)","4":"(45 minutos) Opcional, cargo adicional","5":"(1 hora) Opcional","6":"(45 minutos)","7":"(1 hora)","8":"(30 minutos)","9":"Hurghada, Bah\u00eda de Makadi, Safaga, El Gouna, Sahl Hasheesh"},"itinerary_days_label":{"1":"Lugar de recogida","2":"Van","3":"Hurghada Desert Break time, Sesi\u00f3n informativa sobre seguridad","4":"Paseo en quad por el desierto de Hurghada, vistas panor\u00e1micas por el camino","5":"Paseo en camello por el desierto de Hurghada, Equitaci\u00f3n","6":"Cena en el desierto de Hurghada, espect\u00e1culo de danza tradicional  ","7":"Parada fotogr\u00e1fica en el desierto de Hurghada, Visita tur\u00edstica, Puesta de sol, Vistas panor\u00e1micas en el camino  ","8":"Van","9":"puntos de entrega"},"itinerary_content":{"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":""}},"trip_itinerary_title":"Itinerario","trip_itinerary_description":"","trip_facts_title":"","tab_8_title":"","tab_9_title":"Rese\u00f1as","partial_payment_enable":"","partial_payment_amount":0,"partial_payment_percent":0,"trip_full_payment_enabled":"no","partial_payment_type":"por ciento"},"_s_duration":"7","wpte_gallery_id":{"enable":""},"wte_advanced_itinerary":{"advanced_itinerary":{"itinerary_duration":{"1":0,"2":0,"3":0,"4":0,"5":0,"6":0,"7":0,"8":0,"9":0},"itinerary_duration_type":{"1":"hour","2":"hour","3":"hour","4":"hour","5":"hour","6":"hour","7":"hour","8":"hour","9":"hour"},"sleep_modes":{"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":""},"itinerary_sleep_mode_description":{"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":"","9":""},"meals_included":[],"itinerary_image_max_count":{"1":0,"2":0,"3":0,"4":0,"5":0,"6":0,"7":0,"8":0,"9":0},"itinerary_image":{"1":[],"2":[],"3":[],"4":[],"5":[],"6":[],"7":[],"8":[],"9":[]},"overnight":{"1":{"at":"","altitude":""},"2":{"at":"","altitude":""},"3":{"at":"","altitude":""},"4":{"at":"","altitude":""},"5":{"at":"","altitude":""},"6":{"at":"","altitude":""},"7":{"at":"","altitude":""},"8":{"at":"","altitude":""},"9":{"at":"","altitude":""}}}},"trip_type":"single","trip_duration_minutes":"0","rank_math_internal_links_processed":"1","_wpml_word_count":"16","_wpml_location_migration_done":"1","wp_travel_engine_setting_trip_duration":"7","_s_price":"0","primary_package":"","trip_available_months":"","wp_travel_engine_setting_trip_actual_price":"0","wp_travel_engine_setting_trip_price":"35","trip_expiry_date":"2027-12-31","WTE_Fixed_Starting_Dates_setting":{"availability_title":"","departure_dates":{"section":"1"}},"trip_itinerary_chart_data":"[]","_edit_last":"1","_s_min_pax":"0","_s_max_pax":"0","rank_math_seo_score":"","trip_code":"","_trip_code":"","trustindex_code":"<script defer async src='https:\/\/cdn.trustindex.io\/loader.js?4245b0b506178148ff364f21b02'><\/script>","_trustindex_code":"field_6866471f55c5b","_wpml_media_duplicate":"1","_wpml_media_featured":"1","rank_math_og_content_image":"","_thumbnail_id":"19416","_elementor_edit_mode":"","_elementor_template_type":"","_elementor_version":"","_elementor_pro_version":"","_wp_page_template":"","_elementor_data":"","rank_math_title":"","rank_math_description":"","rank_math_focus_keyword":"","primary_category":0,"_booking_inventory":"","wte_fsd_booked_seats":"","_yoast_wpseo_primary_destination":"","_yoast_wpseo_primary_activities":"","_yoast_wpseo_primary_trip_types":"","_yoast_wpseo_primary_difficulty":"","_yoast_wpseo_estimated-reading-time-minutes":"","_yoast_wpseo_content_score":"","rank_math_primary_destination":"","rank_math_primary_activities":"","rank_math_primary_trip_types":"","rank_math_primary_difficulty":"","rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_clickrank_ai_revert_data":"","rank_math_analytic_object_id":"25","_top_nav_excluded":"","_cms_nav_minihome":"","_last_translation_edit_mode":"translation-editor","_wp_old_slug":"","embed_code":"","_embed_code":"","stripe_product_id":"","max_travellers_per_day":"","wp_travel_engine_featured_trip":"","wpte_vid_gallery":"","_s_difficulty":"","_wpml_post_translation_editor_native":"","wptravelengine_pickup_points":"","rank_math_pillar_content":"","wptravelengine_exclude_dates":"","_wp_old_date":"","_trip_is_package":"","rank_math_ca_keyword":"","code":"FTS-16582","price":"","has_sale":false,"sale_price":"","discount_percent":0,"currency":{"code":"USD","symbol":"&#36;"},"duration":{"days":7,"nights":0,"duration_unit":"horas","duration_type":"days"},"min_pax":"","max_pax":"","discount_value":0,"discount_label":null,"available_times":{"type":"default","items":["2021-1-01","2021-2-01","2021-3-01","2021-4-01","2021-5-01","2021-6-01","2021-7-01","2021-8-01","2021-9-01","2021-10-01","2021-11-01","2021-12-01"]},"description":"<!-- wp:paragraph -->\n<p>Deje atr\u00e1s la ciudad y emb\u00e1rquese en una m\u00e1gica aventura por el desierto en Sahl Hasheesh. Comience su viaje con un emocionante paseo por las dunas doradas, donde podr\u00e1 contemplar el impresionante paisaje del desierto durante la puesta de sol. Al llegar al campamento de estilo beduino, le recibir\u00e1n con hospitalidad tradicional y disfrutar\u00e1 de una cena a la barbacoa reci\u00e9n preparada bajo el cielo abierto.  <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Al caer la noche, sum\u00e9rjase en el silencio y la belleza del desierto. Con la ayuda de gu\u00edas expertos y telescopios de alta potencia, explore las maravillas del cielo nocturno, detecte constelaciones, planetas e incluso galaxias lejanas. Esta experiencia \u00fanica combina aventura, cultura y naturaleza, ofreciendo una escapada tranquila y recuerdos inolvidables.  <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Tanto si viaja en pareja, en familia o en solitario, esta excursi\u00f3n para observar las estrellas es la forma perfecta de disfrutar de la belleza de la noche del desierto egipcio.<\/p>\n<!-- \/wp:paragraph -->","cost_includes":"Recogida en el hotel y regreso desde Sahl Hasheesh o Makadi Bay\nGu\u00eda experimentado en el desierto\nObservaci\u00f3n de las estrellas con telescopio\nVisita al campamento beduino\nHorneado de pan\nEspect\u00e1culo beduino\nEspect\u00e1culo de danza\n5 tipos de platos calientes\nFrutas de temporada (2 tipos diferentes)\nRefresco durante la puesta de sol y la cena\nPaseo de 30 minutos en quad (si se selecciona la opci\u00f3n)","cost_excludes":"","itineraries":[{"title":"Bah\u00eda de Makadi, El Gouna, Sahl Hasheesh, Hurghada, Safaga","content":""},{"title":"(30 minutos)","content":""},{"title":"(15 minutos)","content":""},{"title":"(45 minutos) Opcional, cargo adicional","content":""},{"title":"(1 hora) Opcional","content":""},{"title":"(45 minutos)","content":""},{"title":"(1 hora)","content":""},{"title":"(30 minutos)","content":""},{"title":"Hurghada, Bah\u00eda de Makadi, Safaga, El Gouna, Sahl Hasheesh","content":""}],"faqs":[{"title":"\u00bfQu\u00e9 debo llevar?","content":"<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Gafas de sol<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Sombrero para el sol<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>C\u00e1mara<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Protector solar<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Agua<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Efectivo<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->"},{"title":"\u00bfQu\u00e9 no est\u00e1 permitido?","content":"<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Cochecitos de beb\u00e9<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Maletas o bolsas grandes<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Alcohol y drogas<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->"},{"title":"\u00bfQu\u00e9 debo saber antes de ir?","content":"<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>Por favor, inf\u00f3rmenos del nombre de su hotel y n\u00famero de habitaci\u00f3n despu\u00e9s de reservar para organizar la recogida.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La recogida s\u00f3lo est\u00e1 disponible en los hoteles de Sahl Hasheesh y Makadi Bay; en otras zonas pueden aplicarse cargos adicionales.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La excursi\u00f3n se realiza en todoterreno, por lo que no est\u00e1 recomendada para personas con problemas de movilidad.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La observaci\u00f3n de las estrellas depende de las condiciones meteorol\u00f3gicas y puede modificarse en caso de viento fuerte o nubes.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Pres\u00e9ntese en el vest\u00edbulo del hotel al menos 10 minutos antes de la hora de recogida programada.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->"}],"is_featured":false,"trip_reviews":{"reviews":[],"average":0,"count":0},"featured_image":{"width":2560,"height":1707,"file":"2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-scaled.jpeg","filesize":182636,"sizes":{"medium":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-300x200.jpeg","width":300,"height":200,"filesize":8138,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-300x200.jpeg"},"large":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-1024x683.jpeg","width":1024,"height":683,"filesize":45328,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-1024x683.jpeg"},"thumbnail":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-150x150.jpeg","width":150,"height":150,"filesize":4570,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-150x150.jpeg"},"medium_large":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-768x512.jpeg","width":768,"height":512,"filesize":29519,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-768x512.jpeg"},"trip-thumb-size":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-374x226.jpeg","width":374,"height":226,"filesize":10561,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-374x226.jpeg"},"destination-thumb-size":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-600x810.jpeg","width":600,"height":810,"filesize":34843,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-600x810.jpeg"},"destination-thumb-trip-size":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-410x250.jpeg","width":410,"height":250,"filesize":12051,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-410x250.jpeg"},"activities-thumb-size":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-600x810.jpeg","width":600,"height":810,"filesize":34843,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-600x810.jpeg"},"trip-single-size":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-990x490.jpeg","width":990,"height":490,"filesize":34483,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-990x490.jpeg"},"meafe-featured-page":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-500x410.jpeg","width":500,"height":410,"filesize":18894,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-500x410.jpeg"},"meafe-testimonial-two":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-272x316.jpeg","width":272,"height":316,"filesize":10592,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-272x316.jpeg"},"meafe-blog-one":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-370x247.jpeg","width":370,"height":247,"filesize":10881,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-370x247.jpeg"},"meafe-blog-two":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-197x278.jpeg","width":197,"height":278,"filesize":8012,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-197x278.jpeg"},"meafe-category-tab":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-355x355.jpeg","width":355,"height":355,"filesize":13679,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-355x355.jpeg"},"meafe-category-grid":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-370x370.jpeg","width":370,"height":370,"filesize":14495,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-370x370.jpeg"},"meafe-category-grid-one":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-570x530.jpeg","width":570,"height":530,"filesize":24466,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-570x530.jpeg"},"meafe-category-grid-two":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-270x180.jpeg","width":270,"height":180,"filesize":7221,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-270x180.jpeg"},"meafe-category-grid-three":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-570x320.jpeg","width":570,"height":320,"filesize":17460,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-570x320.jpeg"},"meafe-category-grid-lay-three":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-170x170.jpeg","width":170,"height":170,"filesize":5315,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-170x170.jpeg"},"meafe-post-modules-small-img":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-300x300.jpeg","width":300,"height":300,"filesize":10708,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-300x300.jpeg"},"1536x1536":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-1536x1024.jpeg","width":1536,"height":1024,"filesize":83029,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-1536x1024.jpeg"},"2048x2048":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-2048x1365.jpeg","width":2048,"height":1365,"filesize":129121,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-2048x1365.jpeg"},"travel-monster-fullwidth":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-1290x670.jpeg","width":1290,"height":670,"filesize":52910,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-1290x670.jpeg"},"travel-monster-withsidebar":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-860x510.jpeg","width":860,"height":510,"filesize":32936,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-860x510.jpeg"},"travel-monster-blog-grid":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-415x260.jpeg","width":415,"height":260,"filesize":12251,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-415x260.jpeg"},"travel-monster-latest-post":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-970x655.jpeg","width":970,"height":655,"filesize":42164,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-970x655.jpeg"},"travel-monster-blog-list":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-300x440.jpeg","width":300,"height":440,"filesize":14165,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-300x440.jpeg"},"travel-monster-header-bg-img":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-1920x350.jpeg","width":1920,"height":350,"filesize":34707,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-1920x350.jpeg"},"travel-monster-single-layout-two":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-1920x600.jpeg","width":1920,"height":600,"filesize":60391,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-1920x600.jpeg"},"full":{"file":"249F0574-1498-4C3E-878D-BB13980E8DDC-scaled.jpeg","width":2560,"height":1707,"source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/249F0574-1498-4C3E-878D-BB13980E8DDC-scaled.jpeg"}},"image_meta":{"aperture":"0","credit":"Shutterstock","camera":"","caption":"Girl looking at lunar eclipse through a telescope. My astronomy work.","created_timestamp":"0","copyright":"Copyright (c) 2018 AstroStar\/Shutterstock.  No use without permission.","focal_length":"0","iso":"0","shutter_speed":"0","title":"Girl looking at lunar eclipse through a telescope. My astronomy work.","orientation":"0","keywords":[]},"original_image":"249F0574-1498-4C3E-878D-BB13980E8DDC.jpeg"},"_links":{"self":[{"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/trip\/16587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/trip"}],"about":[{"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/types\/trip"}],"author":[{"embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/comments?post=16587"}],"version-history":[{"count":0,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/trip\/16587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/media\/19416"}],"wp:attachment":[{"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/media?parent=16587"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/destination?post=16587"},{"taxonomy":"activities","embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/activities?post=16587"},{"taxonomy":"trip_types","embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/trip_types?post=16587"},{"taxonomy":"packages","embeddable":true,"href":"https:\/\/fts-travel.com\/es\/wp-json\/wp\/v2\/packages?post=16587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}