{"id":14285,"date":"2025-05-16T19:58:36","date_gmt":"2025-05-16T19:58:36","guid":{"rendered":"https:\/\/fts-travel.com\/tours\/hurghada-entree-au-parc-aquatique-neverland-avec-transferts\/"},"modified":"2025-05-28T18:55:52","modified_gmt":"2025-05-28T18:55:52","slug":"hurghada-neverland-aqua-park-admission-with-transfers","status":"publish","type":"trip","link":"https:\/\/fts-travel.com\/fr\/tours\/hurghada-neverland-aqua-park-admission-with-transfers\/","title":{"rendered":"Hurghada : Entr\u00e9e au parc aquatique Neverland avec transferts"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6693,"comment_status":"open","ping_status":"open","template":"","destination":[130,164],"activities":[129],"trip_types":[],"packages":[],"class_list":["post-14285","trip","type-trip","status-publish","has-post-thumbnail","hentry","destination-egypte","destination-hurghada-fr","activities-excursion-dune-journee","travel-monster-post","latest_post"],"packages_ids":[7830,7831],"trip_extras":[],"cut_off_time":{"enabled":false,"duration":0,"duration_unit":"jours"},"booked-seats":[],"trip_extra_services":{},"acf":[],"trip_version":"2.0.0","_s_has_sale":"yes","_edit_lock":"1748353563:6","total_travellers_per_day":"","wp_travel_engine_setting":{"trip_code":"FTS-6668","overview_section_title":"A propos de cette visite","tab_content":{"1_wpeditor":"<!-- wp:paragraph -->\n<p>Profitez d'une journ\u00e9e de plaisir au parc aquatique Neverland avec un billet d'entr\u00e9e pour une journ\u00e9e enti\u00e8re et le transport aller-retour au d\u00e9part d'Hurghada. D\u00e9couvrez 35 toboggans aquatiques \u00e0 sensations fortes, d\u00e9tendez-vous dans les piscines et sur les chaises longues, et profitez au maximum d'une aventure aquatique inoubliable. <\/p>\n<!-- \/wp:paragraph -->","8_wpeditor":"","9_wpeditor":""},"cost_tab_sec_title":"Inclus","cost":{"includes_title":"Le co\u00fbt comprend","cost_includes":"Billet d'entr\u00e9e au parc pour une journ\u00e9e enti\u00e8re de plaisir aquatique\nD\u00e9jeuner d\u00e9licieux inclus\nPrise en charge et retour \u00e0 l'h\u00f4tel \u00e0 partir d'Hurghada (si suppl\u00e9ment choisi)","excludes_title":"","cost_excludes":""},"trip_duration":7,"trip_duration_unit":"heures","trip_duration_nights":0,"min_max_age_enable":"","trip_cutoff_enable":"","trip_cut_off_time":0,"trip_cut_off_unit":"jours","minmax_pax_enable":"","trip_minimum_pax":0,"trip_maximum_pax":0,"map":{"iframe":""},"map_section_title":"","trip_highlights_title":"Points forts","trip_highlights":[{"highlight_text":"Faites l'exp\u00e9rience de 35 toboggans aquatiques charg\u00e9s d'adr\u00e9naline au parc aquatique Neverland."},{"highlight_text":"Plongez dans 14 piscines ext\u00e9rieures, dont une piscine chauff\u00e9e et une piscine \u00e0 vagues."},{"highlight_text":"Prenez un radeau et descendez la rivi\u00e8re paresseuse, en profitant du soleil pour vous d\u00e9tendre."},{"highlight_text":"D\u00e9tendez-vous sur de confortables chaises longues, faites une pause dans l'action et profitez du temps chaud."},{"highlight_text":"Faites le plein dans l'un des restaurants ou des snack-bars du parc, qui proposent de nombreuses options d\u00e9licieuses."}],"faq_section_title":"Questions fr\u00e9quemment pos\u00e9es","faq":{"faq_title":["Que dois-je savoir avant de partir ?"],"faq_content":["<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>La prise en charge et le retour sont possibles depuis les h\u00f4tels d'Hurghada.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La prise en charge et le retour depuis les h\u00f4tels d'El Gouna, Al Ahyaa, Sahl Hasheesh, Makadi et Soma Bay sont disponibles en suppl\u00e9ment.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>L'organisateur de l'activit\u00e9 vous contactera pour vous communiquer les d\u00e9tails exacts de votre prise en charge. Veuillez envoyer votre num\u00e9ro de chambre par courriel ou par WhatsApp si possible. <\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>L'heure de prise en charge d\u00e9pend de l'emplacement de votre h\u00f4tel - veuillez confirmer l'heure exacte un jour avant le voyage.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Pour toute demande de renseignements, appelez-nous ou envoyez-nous un message WhatsApp au +20 201030774440.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Un d\u00e9lai d'enl\u00e8vement pouvant aller jusqu'\u00e0 10 minutes peut se produire.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->"]},"enable_video_gallery":"","itinerary":{"itinerary_title":{"1":"  Sahl Hasheesh, Hurghada, El Gouna, Safaga, Makadi Bay","2":"(30 minutes)","3":"(6 heures)","4":"(30 minutes)","5":"Baie de Makadi, Safaga, Hurghada, El Gouna, Sahl Hasheesh"},"itinerary_days_label":{"1":"Lieu de ramassage","2":"Fourgon","3":"Jungle Aqua Park Arr\u00eat photo, Visite, D\u00e9jeuner, Temps libre, Baignade  ","4":"Fourgon  ","5":"lieux de d\u00e9p\u00f4t"},"itinerary_content":{"1":"","2":"","3":"","4":"","5":""}},"trip_itinerary_title":"Itin\u00e9raire","trip_facts_title":"","partial_payment_enable":"","partial_payment_amount":0,"partial_payment_percent":0,"trip_full_payment_enabled":"non","partial_payment_type":"pour cent","tab_8_title":"","tab_9_title":""},"_s_duration":"7","wpte_gallery_id":{"enable":"1","0":6693,"1":6689,"2":6691,"3":6692,"4":6694,"5":6695,"6":6696},"wte_advanced_itinerary":{"advanced_itinerary":{"itinerary_image":[]}},"trip_type":"single","trip_duration_minutes":"0","rank_math_internal_links_processed":"1","_wpml_word_count":"11","_wpml_location_migration_done":"","wp_travel_engine_setting_trip_duration":"7","_s_price":"99","primary_package":"7830","trip_available_months":"","wp_travel_engine_setting_trip_actual_price":"120","wp_travel_engine_setting_trip_price":"99","trip_expiry_date":"2025-06-03","WTE_Fixed_Starting_Dates_setting":{"availability_title":"","departure_dates":{"section":"1"}},"trip_itinerary_chart_data":"","_edit_last":"1","_s_min_pax":"0","_s_max_pax":"","rank_math_seo_score":"","trip_code":"","_trip_code":"","trustindex_code":"","_trustindex_code":"","_wpml_media_duplicate":"","_wpml_media_featured":"","rank_math_og_content_image":"","_thumbnail_id":"6693","_elementor_edit_mode":"","_elementor_template_type":"","_elementor_version":"","_elementor_pro_version":"","_wp_page_template":"","_elementor_data":"","rank_math_title":"","rank_math_description":"","rank_math_focus_keyword":"","primary_category":11,"_booking_inventory":"","wte_fsd_booked_seats":"","_yoast_wpseo_primary_destination":"56","_yoast_wpseo_primary_activities":"67","_yoast_wpseo_primary_trip_types":"","_yoast_wpseo_primary_difficulty":"","_yoast_wpseo_estimated-reading-time-minutes":"3","_yoast_wpseo_content_score":"90","rank_math_primary_destination":"56","rank_math_primary_activities":"67","rank_math_primary_trip_types":"","rank_math_primary_difficulty":"","rank_math_news_sitemap_robots":"index","rank_math_robots":["index"],"_clickrank_ai_revert_data":"","rank_math_analytic_object_id":"","_top_nav_excluded":"","_cms_nav_minihome":"","_last_translation_edit_mode":"translation-editor","_wp_old_slug":"hurghada-entree-au-parc-aquatique-neverland-avec-transferts","embed_code":"","_embed_code":"","stripe_product_id":"","max_travellers_per_day":"","wp_travel_engine_featured_trip":"","wpte_vid_gallery":"","_s_difficulty":"","_wpml_post_translation_editor_native":"","wptravelengine_pickup_points":"","rank_math_pillar_content":"","wptravelengine_exclude_dates":"","_wp_old_date":"","_trip_is_package":"","rank_math_ca_keyword":"","code":"FTS-6668","price":120,"has_sale":true,"sale_price":99,"discount_percent":18,"currency":{"code":"USD","symbol":"&#36;"},"duration":{"days":7,"nights":0,"duration_unit":"heures","duration_type":"days"},"min_pax":"","max_pax":"","discount_value":21,"discount_label":"18% Off","available_times":{"type":"default","items":["2021-1-01","2021-2-01","2021-3-01","2021-4-01","2021-5-01","2021-6-01","2021-7-01","2021-8-01","2021-9-01","2021-10-01","2021-11-01","2021-12-01"]},"description":"<!-- wp:paragraph -->\n<p>Profitez d'une journ\u00e9e de plaisir au parc aquatique Neverland avec un billet d'entr\u00e9e pour une journ\u00e9e enti\u00e8re et le transport aller-retour au d\u00e9part d'Hurghada. D\u00e9couvrez 35 toboggans aquatiques \u00e0 sensations fortes, d\u00e9tendez-vous dans les piscines et sur les chaises longues, et profitez au maximum d'une aventure aquatique inoubliable. <\/p>\n<!-- \/wp:paragraph -->","cost_includes":"Billet d'entr\u00e9e au parc pour une journ\u00e9e enti\u00e8re de plaisir aquatique\nD\u00e9jeuner d\u00e9licieux inclus\nPrise en charge et retour \u00e0 l'h\u00f4tel \u00e0 partir d'Hurghada (si suppl\u00e9ment choisi)","cost_excludes":"","itineraries":[{"title":"  Sahl Hasheesh, Hurghada, El Gouna, Safaga, Makadi Bay","content":""},{"title":"(30 minutes)","content":""},{"title":"(6 heures)","content":""},{"title":"(30 minutes)","content":""},{"title":"Baie de Makadi, Safaga, Hurghada, El Gouna, Sahl Hasheesh","content":""}],"faqs":[{"title":"Que dois-je savoir avant de partir ?","content":"<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>La prise en charge et le retour sont possibles depuis les h\u00f4tels d'Hurghada.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>La prise en charge et le retour depuis les h\u00f4tels d'El Gouna, Al Ahyaa, Sahl Hasheesh, Makadi et Soma Bay sont disponibles en suppl\u00e9ment.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>L'organisateur de l'activit\u00e9 vous contactera pour vous communiquer les d\u00e9tails exacts de votre prise en charge. Veuillez envoyer votre num\u00e9ro de chambre par courriel ou par WhatsApp si possible. <\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>L'heure de prise en charge d\u00e9pend de l'emplacement de votre h\u00f4tel - veuillez confirmer l'heure exacte un jour avant le voyage.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Pour toute demande de renseignements, appelez-nous ou envoyez-nous un message WhatsApp au +20 201030774440.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>Un d\u00e9lai d'enl\u00e8vement pouvant aller jusqu'\u00e0 10 minutes peut se produire.<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->"}],"is_featured":false,"trip_reviews":{"reviews":[],"average":0,"count":0},"featured_image":{"width":1200,"height":800,"file":"2025\/05\/Image00004-21.jpg","filesize":273730,"sizes":{"medium":{"file":"Image00004-21-300x200.jpg","width":300,"height":200,"filesize":20059,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-300x200.jpg"},"large":{"file":"Image00004-21-1024x683.jpg","width":1024,"height":683,"filesize":131020,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-1024x683.jpg"},"thumbnail":{"file":"Image00004-21-150x150.jpg","width":150,"height":150,"filesize":9530,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-150x150.jpg"},"medium_large":{"file":"Image00004-21-768x512.jpg","width":768,"height":512,"filesize":84608,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-768x512.jpg"},"trip-thumb-size":{"file":"Image00004-21-374x226.jpg","width":374,"height":226,"filesize":27113,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-374x226.jpg"},"destination-thumb-size":{"file":"Image00004-21-600x800.jpg","width":600,"height":800,"filesize":108016,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-600x800.jpg"},"destination-thumb-trip-size":{"file":"Image00004-21-410x250.jpg","width":410,"height":250,"filesize":31245,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-410x250.jpg"},"activities-thumb-size":{"file":"Image00004-21-600x800.jpg","width":600,"height":800,"filesize":108016,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-600x800.jpg"},"trip-single-size":{"file":"Image00004-21-990x490.jpg","width":990,"height":490,"filesize":105472,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-990x490.jpg"},"meafe-featured-page":{"file":"Image00004-21-500x410.jpg","width":500,"height":410,"filesize":52143,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-500x410.jpg"},"meafe-testimonial-two":{"file":"Image00004-21-272x316.jpg","width":272,"height":316,"filesize":26689,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-272x316.jpg"},"meafe-blog-one":{"file":"Image00004-21-370x247.jpg","width":370,"height":247,"filesize":27795,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-370x247.jpg"},"meafe-blog-two":{"file":"Image00004-21-197x278.jpg","width":197,"height":278,"filesize":19010,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-197x278.jpg"},"meafe-category-tab":{"file":"Image00004-21-355x355.jpg","width":355,"height":355,"filesize":36210,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-355x355.jpg"},"meafe-category-grid":{"file":"Image00004-21-370x370.jpg","width":370,"height":370,"filesize":38663,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-370x370.jpg"},"meafe-category-grid-one":{"file":"Image00004-21-570x530.jpg","width":570,"height":530,"filesize":70035,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-570x530.jpg"},"meafe-category-grid-two":{"file":"Image00004-21-270x180.jpg","width":270,"height":180,"filesize":16833,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-270x180.jpg"},"meafe-category-grid-three":{"file":"Image00004-21-570x320.jpg","width":570,"height":320,"filesize":49597,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-570x320.jpg"},"meafe-category-grid-lay-three":{"file":"Image00004-21-170x170.jpg","width":170,"height":170,"filesize":11651,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-170x170.jpg"},"meafe-post-modules-small-img":{"file":"Image00004-21-300x300.jpg","width":300,"height":300,"filesize":28007,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-300x300.jpg"},"travel-monster-fullwidth":{"file":"Image00004-21-1200x670.jpg","width":1200,"height":670,"filesize":167249,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-1200x670.jpg"},"travel-monster-withsidebar":{"file":"Image00004-21-860x510.jpg","width":860,"height":510,"filesize":96423,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-860x510.jpg"},"travel-monster-blog-grid":{"file":"Image00004-21-415x260.jpg","width":415,"height":260,"filesize":32058,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-415x260.jpg"},"travel-monster-latest-post":{"file":"Image00004-21-970x655.jpg","width":970,"height":655,"filesize":122296,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-970x655.jpg"},"travel-monster-blog-list":{"file":"Image00004-21-300x440.jpg","width":300,"height":440,"filesize":37378,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-300x440.jpg"},"travel-monster-header-bg-img":{"file":"Image00004-21-1200x350.jpg","width":1200,"height":350,"filesize":94752,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-1200x350.jpg"},"travel-monster-single-layout-two":{"file":"Image00004-21-1200x600.jpg","width":1200,"height":600,"filesize":153616,"mime_type":"image\/jpeg","source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21-1200x600.jpg"},"full":{"file":"Image00004-21.jpg","width":1200,"height":800,"source_url":"https:\/\/fts-travel.com\/wp-content\/uploads\/2025\/05\/Image00004-21.jpg"}},"image_meta":{"aperture":"7.1","credit":"Photographer:Sergey Novikov (Ser","camera":"Canon EOS 5D Mark II","caption":"Girl in a group of teenage children have fun in the swimming pool diving with inflatable toys doughnuts, matrass jump and splash in the water","created_timestamp":"1593364031","copyright":"Copyright:Sergey Novikov (SerrNovik) ripicts.com","focal_length":"20","iso":"100","shutter_speed":"0.0025","title":"Girl and friends dive in swim pool splash to water","orientation":"1","keywords":["jump","pool","child","kids","action","summer","fun","water","splash","vacation","children","kid","boy","boys","handsome","bikini","girl","girls","teen","teenager","active","swimsuit","Caucasian","donut","ring","inflatable","swim","buoy","toy","doughnut","noodle","mattress","lifestyle","activity","motion","party","many","group","friends","happy","team","together","outdoor","air","hands up","lift","smile","laugh","teens","teenagers"]}},"_links":{"self":[{"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/trip\/14285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/trip"}],"about":[{"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/types\/trip"}],"author":[{"embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/comments?post=14285"}],"version-history":[{"count":0,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/trip\/14285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/media\/6693"}],"wp:attachment":[{"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/media?parent=14285"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/destination?post=14285"},{"taxonomy":"activities","embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/activities?post=14285"},{"taxonomy":"trip_types","embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/trip_types?post=14285"},{"taxonomy":"packages","embeddable":true,"href":"https:\/\/fts-travel.com\/fr\/wp-json\/wp\/v2\/packages?post=14285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}